{"id":455,"date":"2019-02-25T12:10:33","date_gmt":"2019-02-25T15:10:33","guid":{"rendered":"http:\/\/camarapocao.pe.gov.br\/v1\/?page_id=455"},"modified":"2019-02-25T12:10:33","modified_gmt":"2019-02-25T15:10:33","slug":"licitacoes-aprovadas-em-2014","status":"publish","type":"page","link":"https:\/\/camarapocao.pe.gov.br\/v1\/licitacoes-aprovadas-em-2014\/","title":{"rendered":"Licita\u00e7\u00f5es aprovadas em 2014"},"content":{"rendered":"\n<table class=\"wp-block-table is-style-stripes\"><tbody><tr><td><strong>N\u00ba do documento<\/strong><\/td><td><strong>Descri\u00e7\u00e3o<\/strong><\/td><td><strong>Download<\/strong><\/td><\/tr><tr><td>01<\/td><td>(COMPRA N\u00c3O\n EFETIVADA)Processo licitat\u00f3rio na modalidade carta convite para \naquisi\u00e7\u00e3o de 01 (um) ve\u00edculo, carro de fabrica\u00e7\u00e3o nacional, zero km, ano\n de fabrica\u00e7\u00e3o 2014&#8230;<\/td><td><a href=\"http:\/\/www.camarapocao.pe.gov.br\/home\/images\/Consulta\/licitacoes\/2014\/01-2014.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">PDF<\/a><\/td><\/tr><tr><td>02<\/td><td>(COMPRA \nEFETIVADA)Processo licitat\u00f3rio na modalidade carta convite para \naquisi\u00e7\u00e3o de 01 (um) ve\u00edculo, carro de fabrica\u00e7\u00e3o nacional, zero km, ano\n de fabrica\u00e7\u00e3o 2014&#8230;<\/td><td><a href=\"http:\/\/www.camarapocao.pe.gov.br\/home\/images\/Consulta\/licitacoes\/2014\/02-2014.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">PDF<\/a><\/td><\/tr><\/tbody><\/table>\n","protected":false},"excerpt":{"rendered":"<p>N\u00ba do documento Descri\u00e7\u00e3o Download 01 (COMPRA N\u00c3O EFETIVADA)Processo licitat\u00f3rio na modalidade carta convite para aquisi\u00e7\u00e3o de 01 (um) ve\u00edculo, carro de fabrica\u00e7\u00e3o nacional, zero <a class=\"leiamais\" href=\"https:\/\/camarapocao.pe.gov.br\/v1\/licitacoes-aprovadas-em-2014\/\"><i class=\"fa fa-angle-double-right\" aria-hidden=\"true\"><\/i><br \/>\n<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-455","page","type-page","status-publish","hentry","active"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/pages\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":1,"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/pages\/455\/revisions"}],"predecessor-version":[{"id":456,"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/pages\/455\/revisions\/456"}],"wp:attachment":[{"href":"https:\/\/camarapocao.pe.gov.br\/v1\/wp-json\/wp\/v2\/media?parent=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}